{"id":6596,"date":"2019-04-17T06:00:39","date_gmt":"2019-04-17T04:00:39","guid":{"rendered":"https:\/\/k-engelhardt.de\/wahnsinn\/?p=6596"},"modified":"2019-01-05T21:33:11","modified_gmt":"2019-01-05T19:33:11","slug":"kennst-du-den-65","status":"publish","type":"post","link":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/","title":{"rendered":"Kennst du den? #65"},"content":{"rendered":"\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full alignleft\" alt=\"Humor\" src=\"http:\/\/www.k-engelhardt.de\/wahnsinn\/wp-content\/uploads\/2013\/01\/Humor-1701.jpg\" width=\"171\" height=\"129\">\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\nGehen zwei Narren auf der Stra\u00dfe. Findet einer einen Spiegel und schaut hinein.\n\u201eHey, den kenn ich doch irgendwie?\u201c <br>\nDer andere schaut hinein und sagt: \u201eKlar kennst du den, das bin doch ich.\u201c <br>\nEr nimmt den Spiegel mit nach Hause. Dort kommt ihm seine Tochter entgegen und schaut schockiert in den Spiegel: \u201eMama, der Papa hat eine Freundin.\u201c <br>\nSchnell kommt die Mama herbeigerannt: \u201eOh Gott, die sieht ja Schei\u00dfe aus.\u201c\n\n\n\n<p><center>*************<\/center><\/p>\n\n\n\nDer eitle Herr Bluck st\u00f6\u00dft im Warenhaus seine Frau an. <br>\n\u201eHast du bemerkt, Emilie, wie mich die h\u00fcbsche Verk\u00e4uferin eben angelacht hat?\u201c <br>\n\u201eSei deswegen nicht traurig\u201c, sagte seine Frau. \u201eIch musste auch lachen, als ich dich das erste Mal sah.\u201c\n\n\n\n<p><center>*************<\/center><\/p>\n\n\n\n\u201eSagen Sie mal, Berger\u201c, sagt der Direktor zu einem j\u00fcngeren Angestellten, \u201eist etwas zwischen Ihnen und meiner Tochter?\u201c <br>\n\u201eGenaugenommen nur Sie, Herr Direktor\u201c, meint der junge Mann. \n","protected":false},"excerpt":{"rendered":"<p>Gehen zwei Narren auf der Stra\u00dfe. Findet einer einen Spiegel und schaut hinein. \u201eHey, den kenn ich doch irgendwie?\u201c Der andere schaut hinein und sagt: \u201eKlar kennst du den, das bin doch ich.\u201c Er nimmt den Spiegel mit nach Hause. Dort kommt ihm seine Tochter entgegen und schaut schockiert in den Spiegel: \u201eMama, der Papa hat eine Freundin.\u201c Schnell kommt die Mama herbeigerannt: \u201eOh Gott, die sieht ja Schei\u00dfe aus.\u201c Der eitle Herr Bluck st\u00f6\u00dft im Warenhaus seine Frau an&#8230;.<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/\">Weiterlesen<span class=\"screen-reader-text\"> Weiterlesen<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-6596","post","type-post","status-publish","format-standard","hentry","category-humor"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Klaus Engelhardt\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Der allt\u00e4gliche Wahnsinn | \u00fcber Inkompetenz und Dummheit\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kennst du den? #65 | Der allt\u00e4gliche Wahnsinn\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-04-17T04:00:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-01-05T19:33:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kennst du den? #65 | Der allt\u00e4gliche Wahnsinn\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/#article\",\"name\":\"Kennst du den? #65 | Der allt\\u00e4gliche Wahnsinn\",\"headline\":\"Kennst du den? #65\",\"author\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\"},\"datePublished\":\"2019-04-17T06:00:39+01:00\",\"dateModified\":\"2019-01-05T21:33:11+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/#webpage\"},\"articleSection\":\"Humor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"name\":\"Humor\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"position\":2,\"name\":\"Humor\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/#listItem\",\"name\":\"Kennst du den? #65\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/#listItem\",\"position\":3,\"name\":\"Kennst du den? #65\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"name\":\"Humor\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\",\"name\":\"Der allt\\u00e4gliche Wahnsinn\",\"description\":\"\\u00fcber Inkompetenz und Dummheit\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/\",\"name\":\"Klaus Engelhardt\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/#webpage\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/\",\"name\":\"Kennst du den? #65 | Der allt\\u00e4gliche Wahnsinn\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/04\\\/kennst-du-den-65\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"datePublished\":\"2019-04-17T06:00:39+01:00\",\"dateModified\":\"2019-01-05T21:33:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#website\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/\",\"name\":\"Der allt\\u00e4gliche Wahnsinn\",\"description\":\"\\u00fcber Inkompetenz und Dummheit\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kennst du den? #65 | Der allt\u00e4gliche Wahnsinn","description":"","canonical_url":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/#article","name":"Kennst du den? #65 | Der allt\u00e4gliche Wahnsinn","headline":"Kennst du den? #65","author":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"publisher":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization"},"datePublished":"2019-04-17T06:00:39+01:00","dateModified":"2019-01-05T21:33:11+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/#webpage"},"isPartOf":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/#webpage"},"articleSection":"Humor"},{"@type":"BreadcrumbList","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn#listItem","position":1,"name":"Home","item":"https:\/\/k-engelhardt.de\/wahnsinn","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","name":"Humor"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","position":2,"name":"Humor","item":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/#listItem","name":"Kennst du den? #65"},"previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/#listItem","position":3,"name":"Kennst du den? #65","previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","name":"Humor"}}]},{"@type":"Organization","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization","name":"Der allt\u00e4gliche Wahnsinn","description":"\u00fcber Inkompetenz und Dummheit","url":"https:\/\/k-engelhardt.de\/wahnsinn\/"},{"@type":"Person","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author","url":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/","name":"Klaus Engelhardt"},{"@type":"WebPage","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/#webpage","url":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/","name":"Kennst du den? #65 | Der allt\u00e4gliche Wahnsinn","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#website"},"breadcrumb":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/#breadcrumblist"},"author":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"creator":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"datePublished":"2019-04-17T06:00:39+01:00","dateModified":"2019-01-05T21:33:11+01:00"},{"@type":"WebSite","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#website","url":"https:\/\/k-engelhardt.de\/wahnsinn\/","name":"Der allt\u00e4gliche Wahnsinn","description":"\u00fcber Inkompetenz und Dummheit","inLanguage":"de-DE","publisher":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Der allt\u00e4gliche Wahnsinn | \u00fcber Inkompetenz und Dummheit","og:type":"article","og:title":"Kennst du den? #65 | Der allt\u00e4gliche Wahnsinn","og:url":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/","article:published_time":"2019-04-17T04:00:39+00:00","article:modified_time":"2019-01-05T19:33:11+00:00","twitter:card":"summary","twitter:title":"Kennst du den? #65 | Der allt\u00e4gliche Wahnsinn"},"aioseo_meta_data":{"post_id":"6596","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-29 12:39:09","updated":"2025-06-04 18:02:40","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/wahnsinn\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/\" title=\"Humor\">Humor<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKennst du den? #65\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/k-engelhardt.de\/wahnsinn"},{"label":"Humor","link":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/"},{"label":"Kennst du den? #65","link":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/04\/kennst-du-den-65\/"}],"_links":{"self":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/6596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/comments?post=6596"}],"version-history":[{"count":1,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/6596\/revisions"}],"predecessor-version":[{"id":6597,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/6596\/revisions\/6597"}],"wp:attachment":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/media?parent=6596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/categories?post=6596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/tags?post=6596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}