{"id":6586,"date":"2019-03-06T06:00:36","date_gmt":"2019-03-06T04:00:36","guid":{"rendered":"https:\/\/k-engelhardt.de\/wahnsinn\/?p=6586"},"modified":"2024-02-01T20:53:40","modified_gmt":"2024-02-01T19:53:40","slug":"kennst-du-den-59-2","status":"publish","type":"post","link":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/","title":{"rendered":"Kennst du den? #59"},"content":{"rendered":"\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full alignleft\" alt=\"Humor\" src=\"http:\/\/www.k-engelhardt.de\/wahnsinn\/wp-content\/uploads\/2013\/01\/Humor-1701.jpg\" width=\"171\" height=\"129\">\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\r\n\r\n\r\n<p>Der junge Anwalt hatte einen Verkehrss\u00fcnder zu verteidigen. Er wollte seine Sache besonders gut machen, so sagte er in seinem Pl\u00e4doyer: <br \/>\u201eDer Angeklagte ist ein sehr vorsichtiger Fahrer. Nie w\u00fcrde er einen Wagen \u00fcberholen, der schneller f\u00e4hrt als seiner.\u201c<\/p>\r\n\r\n\r\n\n<p><center>*************<\/center><\/p>\n\r\n\r\n\r\n<p>Rita reitet mit ihrem Pony aus. Unterwegs fragen zwei kleine Jungen, ob sie das Pony streicheln d\u00fcrfen. Nat\u00fcrlich ist Rita einverstanden. <br \/>Da fragt der eine: \u201eIst das Pony ein M\u00e4dchen oder ein Junge?\u201c<br \/>\u201eEin M\u00e4dchen.\u201c <br \/>\u201eSiehst du\u201c, wendet sich der Junge triumphierend an seinen Freund, \u201eich habe es dir doch gleich gesagt, dass es ein M\u00e4dchen ist, wo es doch so lange Haare hat.\u201c<\/p>\r\n\r\n\r\n\n<p><center>*************<\/center><\/p>\n\r\n\r\n\r\n<p>\u201eMutti, stimmt es denn nicht, dass die Babys aus dem Bauch kommen?\u201c<br \/>\u201eDoch, wieso?\u201c<br \/>\u201eWeil Tante Mathilde gesagt hat, ich sei dir wie aus dem Gesicht geschnitten.\u201c<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Der junge Anwalt hatte einen Verkehrss\u00fcnder zu verteidigen. Er wollte seine Sache besonders gut machen, so sagte er in seinem Pl\u00e4doyer: \u201eDer Angeklagte ist ein sehr vorsichtiger Fahrer. Nie w\u00fcrde er einen Wagen \u00fcberholen, der schneller f\u00e4hrt als seiner.\u201c Rita reitet mit ihrem Pony aus. Unterwegs fragen zwei kleine Jungen, ob sie das Pony streicheln d\u00fcrfen. Nat\u00fcrlich ist Rita einverstanden. Da fragt der eine: \u201eIst das Pony ein M\u00e4dchen oder ein Junge?\u201c\u201eEin M\u00e4dchen.\u201c \u201eSiehst du\u201c, wendet sich der Junge triumphierend&#8230;<\/p>\n<p class=\"read-more\"><a class=\"btn btn-default\" href=\"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/\">Weiterlesen<span class=\"screen-reader-text\"> Weiterlesen<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-6586","post","type-post","status-publish","format-standard","hentry","category-humor"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Klaus Engelhardt\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Der allt\u00e4gliche Wahnsinn | \u00fcber Inkompetenz und Dummheit\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kennst du den? #59 | Der allt\u00e4gliche Wahnsinn\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-03-06T04:00:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-01T19:53:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kennst du den? #59 | Der allt\u00e4gliche Wahnsinn\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/#article\",\"name\":\"Kennst du den? #59 | Der allt\\u00e4gliche Wahnsinn\",\"headline\":\"Kennst du den? #59\",\"author\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\"},\"datePublished\":\"2019-03-06T06:00:36+01:00\",\"dateModified\":\"2024-02-01T20:53:40+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/#webpage\"},\"articleSection\":\"Humor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"name\":\"Humor\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"position\":2,\"name\":\"Humor\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/#listItem\",\"name\":\"Kennst du den? #59\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/#listItem\",\"position\":3,\"name\":\"Kennst du den? #59\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"name\":\"Humor\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\",\"name\":\"Der allt\\u00e4gliche Wahnsinn\",\"description\":\"\\u00fcber Inkompetenz und Dummheit\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/\",\"name\":\"Klaus Engelhardt\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/#webpage\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/\",\"name\":\"Kennst du den? #59 | Der allt\\u00e4gliche Wahnsinn\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2019\\\/03\\\/kennst-du-den-59-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"datePublished\":\"2019-03-06T06:00:36+01:00\",\"dateModified\":\"2024-02-01T20:53:40+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#website\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/\",\"name\":\"Der allt\\u00e4gliche Wahnsinn\",\"description\":\"\\u00fcber Inkompetenz und Dummheit\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kennst du den? #59 | Der allt\u00e4gliche Wahnsinn","description":"","canonical_url":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/#article","name":"Kennst du den? #59 | Der allt\u00e4gliche Wahnsinn","headline":"Kennst du den? #59","author":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"publisher":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization"},"datePublished":"2019-03-06T06:00:36+01:00","dateModified":"2024-02-01T20:53:40+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/#webpage"},"isPartOf":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/#webpage"},"articleSection":"Humor"},{"@type":"BreadcrumbList","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn#listItem","position":1,"name":"Home","item":"https:\/\/k-engelhardt.de\/wahnsinn","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","name":"Humor"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","position":2,"name":"Humor","item":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/#listItem","name":"Kennst du den? #59"},"previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/#listItem","position":3,"name":"Kennst du den? #59","previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","name":"Humor"}}]},{"@type":"Organization","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization","name":"Der allt\u00e4gliche Wahnsinn","description":"\u00fcber Inkompetenz und Dummheit","url":"https:\/\/k-engelhardt.de\/wahnsinn\/"},{"@type":"Person","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author","url":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/","name":"Klaus Engelhardt"},{"@type":"WebPage","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/#webpage","url":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/","name":"Kennst du den? #59 | Der allt\u00e4gliche Wahnsinn","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#website"},"breadcrumb":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/#breadcrumblist"},"author":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"creator":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"datePublished":"2019-03-06T06:00:36+01:00","dateModified":"2024-02-01T20:53:40+01:00"},{"@type":"WebSite","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#website","url":"https:\/\/k-engelhardt.de\/wahnsinn\/","name":"Der allt\u00e4gliche Wahnsinn","description":"\u00fcber Inkompetenz und Dummheit","inLanguage":"de-DE","publisher":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Der allt\u00e4gliche Wahnsinn | \u00fcber Inkompetenz und Dummheit","og:type":"article","og:title":"Kennst du den? #59 | Der allt\u00e4gliche Wahnsinn","og:url":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/","article:published_time":"2019-03-06T04:00:36+00:00","article:modified_time":"2024-02-01T19:53:40+00:00","twitter:card":"summary","twitter:title":"Kennst du den? #59 | Der allt\u00e4gliche Wahnsinn"},"aioseo_meta_data":{"post_id":"6586","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-29 12:39:09","updated":"2025-06-04 17:50:23","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/wahnsinn\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/\" title=\"Humor\">Humor<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKennst du den? #59\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/k-engelhardt.de\/wahnsinn"},{"label":"Humor","link":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/"},{"label":"Kennst du den? #59","link":"https:\/\/k-engelhardt.de\/wahnsinn\/2019\/03\/kennst-du-den-59-2\/"}],"_links":{"self":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/6586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/comments?post=6586"}],"version-history":[{"count":2,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/6586\/revisions"}],"predecessor-version":[{"id":8361,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/6586\/revisions\/8361"}],"wp:attachment":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/media?parent=6586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/categories?post=6586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/tags?post=6586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}