{"id":2507,"date":"2015-01-21T06:00:01","date_gmt":"2015-01-21T05:00:01","guid":{"rendered":"http:\/\/www.k-engelhardt.de\/wahnsinn\/?p=2507"},"modified":"2015-01-17T10:32:31","modified_gmt":"2015-01-17T09:32:31","slug":"ein-schwaechliches-kind","status":"publish","type":"post","link":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/","title":{"rendered":"Ein schw\u00e4chliches Kind"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1475 alignleft\" alt=\"Humor - 170\" src=\"http:\/\/www.k-engelhardt.de\/wahnsinn\/wp-content\/uploads\/2013\/01\/Humor-1701.jpg\" width=\"171\" height=\"129\" \/><\/p>\n<p style=\"text-align: justify;\">Der Huberbauer stirbt mit 74. Seine 96j\u00e4hrige Mutter sagt beim Leichenschmaus zum Herrn Pfarrer:<\/p>\n<p style=\"text-align: justify;\">\u201eJa, ja, mein Bub war halt schon immer ein schw\u00e4chliches Kind. Habe es mir doch gleich gedacht, dass ich ihn nicht durchbringe\u2026\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Huberbauer stirbt mit 74. Seine 96j\u00e4hrige Mutter sagt beim Leichenschmaus zum Herrn Pfarrer: \u201eJa, ja, mein Bub war halt schon immer ein schw\u00e4chliches Kind. Habe es mir doch gleich gedacht, dass ich ihn nicht durchbringe\u2026\u201c<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2507","post","type-post","status-publish","format-standard","hentry","category-humor"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Klaus Engelhardt\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Der allt\u00e4gliche Wahnsinn | \u00fcber Inkompetenz und Dummheit\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ein schw\u00e4chliches Kind | Der allt\u00e4gliche Wahnsinn\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-01-21T05:00:01+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-01-17T09:32:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ein schw\u00e4chliches Kind | Der allt\u00e4gliche Wahnsinn\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#article\",\"name\":\"Ein schw\\u00e4chliches Kind | Der allt\\u00e4gliche Wahnsinn\",\"headline\":\"Ein schw\\u00e4chliches Kind\",\"author\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.k-engelhardt.de\\\/wahnsinn\\\/wp-content\\\/uploads\\\/2013\\\/01\\\/Humor-1701.jpg\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#articleImage\"},\"datePublished\":\"2015-01-21T06:00:01+01:00\",\"dateModified\":\"2015-01-17T10:32:31+01:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#webpage\"},\"articleSection\":\"Humor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"name\":\"Humor\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"position\":2,\"name\":\"Humor\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#listItem\",\"name\":\"Ein schw\\u00e4chliches Kind\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#listItem\",\"position\":3,\"name\":\"Ein schw\\u00e4chliches Kind\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/category\\\/humor\\\/#listItem\",\"name\":\"Humor\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\",\"name\":\"Der allt\\u00e4gliche Wahnsinn\",\"description\":\"\\u00fcber Inkompetenz und Dummheit\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/\",\"name\":\"Klaus Engelhardt\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#webpage\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/\",\"name\":\"Ein schw\\u00e4chliches Kind | Der allt\\u00e4gliche Wahnsinn\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/2015\\\/01\\\/ein-schwaechliches-kind\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/author\\\/ichwerdirre465\\\/#author\"},\"datePublished\":\"2015-01-21T06:00:01+01:00\",\"dateModified\":\"2015-01-17T10:32:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#website\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/\",\"name\":\"Der allt\\u00e4gliche Wahnsinn\",\"description\":\"\\u00fcber Inkompetenz und Dummheit\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/wahnsinn\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ein schw\u00e4chliches Kind | Der allt\u00e4gliche Wahnsinn","description":"","canonical_url":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#article","name":"Ein schw\u00e4chliches Kind | Der allt\u00e4gliche Wahnsinn","headline":"Ein schw\u00e4chliches Kind","author":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"publisher":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.k-engelhardt.de\/wahnsinn\/wp-content\/uploads\/2013\/01\/Humor-1701.jpg","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#articleImage"},"datePublished":"2015-01-21T06:00:01+01:00","dateModified":"2015-01-17T10:32:31+01:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#webpage"},"isPartOf":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#webpage"},"articleSection":"Humor"},{"@type":"BreadcrumbList","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn#listItem","position":1,"name":"Home","item":"https:\/\/k-engelhardt.de\/wahnsinn","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","name":"Humor"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","position":2,"name":"Humor","item":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#listItem","name":"Ein schw\u00e4chliches Kind"},"previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#listItem","position":3,"name":"Ein schw\u00e4chliches Kind","previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/#listItem","name":"Humor"}}]},{"@type":"Organization","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization","name":"Der allt\u00e4gliche Wahnsinn","description":"\u00fcber Inkompetenz und Dummheit","url":"https:\/\/k-engelhardt.de\/wahnsinn\/"},{"@type":"Person","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author","url":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/","name":"Klaus Engelhardt"},{"@type":"WebPage","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#webpage","url":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/","name":"Ein schw\u00e4chliches Kind | Der allt\u00e4gliche Wahnsinn","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#website"},"breadcrumb":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/#breadcrumblist"},"author":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"creator":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/author\/ichwerdirre465\/#author"},"datePublished":"2015-01-21T06:00:01+01:00","dateModified":"2015-01-17T10:32:31+01:00"},{"@type":"WebSite","@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#website","url":"https:\/\/k-engelhardt.de\/wahnsinn\/","name":"Der allt\u00e4gliche Wahnsinn","description":"\u00fcber Inkompetenz und Dummheit","inLanguage":"de-DE","publisher":{"@id":"https:\/\/k-engelhardt.de\/wahnsinn\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Der allt\u00e4gliche Wahnsinn | \u00fcber Inkompetenz und Dummheit","og:type":"article","og:title":"Ein schw\u00e4chliches Kind | Der allt\u00e4gliche Wahnsinn","og:url":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/","article:published_time":"2015-01-21T05:00:01+00:00","article:modified_time":"2015-01-17T09:32:31+00:00","twitter:card":"summary","twitter:title":"Ein schw\u00e4chliches Kind | Der allt\u00e4gliche Wahnsinn"},"aioseo_meta_data":{"post_id":"2507","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-29 12:51:09","updated":"2025-06-04 11:12:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/wahnsinn\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/\" title=\"Humor\">Humor<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEin schw\u00e4chliches Kind\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/k-engelhardt.de\/wahnsinn"},{"label":"Humor","link":"https:\/\/k-engelhardt.de\/wahnsinn\/category\/humor\/"},{"label":"Ein schw\u00e4chliches Kind","link":"https:\/\/k-engelhardt.de\/wahnsinn\/2015\/01\/ein-schwaechliches-kind\/"}],"_links":{"self":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/2507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/comments?post=2507"}],"version-history":[{"count":2,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/2507\/revisions"}],"predecessor-version":[{"id":2509,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/posts\/2507\/revisions\/2509"}],"wp:attachment":[{"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/media?parent=2507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/categories?post=2507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/k-engelhardt.de\/wahnsinn\/wp-json\/wp\/v2\/tags?post=2507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}