{"id":5964,"date":"2016-10-02T06:00:57","date_gmt":"2016-10-02T05:00:57","guid":{"rendered":"http:\/\/k-engelhardt.de\/knobeleien\/?p=5964"},"modified":"2017-01-02T19:00:26","modified_gmt":"2017-01-02T18:00:26","slug":"die-verschwundenen-rechenzeichen-24","status":"publish","type":"post","link":"https:\/\/k-engelhardt.de\/knobeleien\/die-verschwundenen-rechenzeichen-24\/","title":{"rendered":"Die verschwundenen Rechenzeichen #24"},"content":{"rendered":"<table>\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-256 alignleft\" title=\"cat-die-verschwundenen-rechenzeichen\" src=\"http:\/\/k-engelhardt.de\/wahnsinn\/wp-content\/uploads\/2016\/03\/wanted-1.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><br \/>\nWer findet die richtigen Rechenzeichen, damit die folgenden Gleichungen stimmen?<br \/>\nBeispiel: 2 7 3 = 6; L\u00f6sung: 2 + 7 &#8211; 3 = 6. Denkt bitte daran: Punktrechnung geht vor Strichrechnung. Ich m\u00f6chte euch den R\u00e4tselspa\u00df nicht nehmen. Darum verrate ich euch die Antwort erst, wenn die Aufgabe gel\u00f6st wurde oder mich jemand per Kommentar darum bittet.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>a) 6\u00a0\u00a0 4\u00a0\u00a0 9\u00a0\u00a0 6 = 3 (mindestens 1 L\u00f6sung)<br \/>\nb) 9\u00a0\u00a0 3\u00a0\u00a0 8\u00a0\u00a0 4\u00a0\u00a0 4 = 6\u00a0 (mindestens 4 L\u00f6sungen)<br \/>\nc) 3\u00a0\u00a0 2\u00a0\u00a0 4\u00a0\u00a0 1\u00a0\u00a0 2\u00a0\u00a0 1 = 8\u00a0 (mindestens 33 L\u00f6sungen)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer findet die richtigen Rechenzeichen, damit die folgenden Gleichungen stimmen? Beispiel: 2 7 3 = 6; L\u00f6sung: 2 + 7 &#8211; 3 = 6. Denkt bitte daran: Punktrechnung geht vor Strichrechnung. Ich m\u00f6chte euch den R\u00e4tselspa\u00df nicht nehmen. Darum verrate &hellip; <a href=\"https:\/\/k-engelhardt.de\/knobeleien\/die-verschwundenen-rechenzeichen-24\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-5964","post","type-post","status-publish","format-standard","hentry","category-mathematische-raetsel"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/5964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/comments?post=5964"}],"version-history":[{"count":3,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/5964\/revisions"}],"predecessor-version":[{"id":6134,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/5964\/revisions\/6134"}],"wp:attachment":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/media?parent=5964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/categories?post=5964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/tags?post=5964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}