{"id":5783,"date":"2016-10-01T06:00:36","date_gmt":"2016-10-01T05:00:36","guid":{"rendered":"http:\/\/k-engelhardt.de\/knobeleien\/?p=5783"},"modified":"2016-05-03T12:11:03","modified_gmt":"2016-05-03T11:11:03","slug":"wortspalterei-178","status":"publish","type":"post","link":"https:\/\/k-engelhardt.de\/knobeleien\/wortspalterei-178\/","title":{"rendered":"Wortspalterei #178"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-256 alignleft\" title=\"cat-wortspalterei\" src=\"http:\/\/www.k-engelhardt.de\/knobeleien\/wp-content\/uploads\/2012\/06\/cat-wortspalterei.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>Wir zerlegen ein Wort in seine Buchstaben und formen damit neue W\u00f6rter. Aus WORT w\u00fcrde etwa WO, ORT, ROT oder TOR.<\/p>\n<p>Das zu zerlegende Wort der Woche hei\u00dft <strong>FEUERWERK<\/strong>.<br \/>\nIch habe daraus 18 neue W\u00f6rter bilden k\u00f6nnen. Wer findet sie alle &#8211; und vielleicht sogar mehr?<br \/>\nIch m\u00f6chte euch den R\u00e4tselspa\u00df nicht nehmen. Darum verrate ich euch die Antwort erst, wenn die Aufgabe gel\u00f6st wurde oder mich jemand per Kommentar darum bittet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir zerlegen ein Wort in seine Buchstaben und formen damit neue W\u00f6rter. Aus WORT w\u00fcrde etwa WO, ORT, ROT oder TOR. Das zu zerlegende Wort der Woche hei\u00dft FEUERWERK. Ich habe daraus 18 neue W\u00f6rter bilden k\u00f6nnen. Wer findet sie &hellip; <a href=\"https:\/\/k-engelhardt.de\/knobeleien\/wortspalterei-178\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5783","post","type-post","status-publish","format-standard","hentry","category-wortspalterei"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/5783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/comments?post=5783"}],"version-history":[{"count":1,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/5783\/revisions"}],"predecessor-version":[{"id":5784,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/5783\/revisions\/5784"}],"wp:attachment":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/media?parent=5783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/categories?post=5783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/tags?post=5783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}