{"id":2301,"date":"2013-09-23T07:00:22","date_gmt":"2013-09-23T06:00:22","guid":{"rendered":"http:\/\/www.k-engelhardt.de\/knobeleien\/?p=2301"},"modified":"2013-09-21T10:01:45","modified_gmt":"2013-09-21T09:01:45","slug":"wortpuzzle-87-beziehungskiste","status":"publish","type":"post","link":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/","title":{"rendered":"Wortpuzzle #87 &#8211; Beziehungskiste"},"content":{"rendered":"<table>\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-256 alignleft\" title=\"cat-wortpuzzle\" alt=\"\" src=\"http:\/\/www.k-engelhardt.de\/knobeleien\/wp-content\/uploads\/2012\/09\/cat-wortpuzzle.jpg\" width=\"150\" height=\"150\" \/>Hilfe, die Buchstaben dieses Wortes haben sich komplett neu sortiert. Doch wie war das urspr\u00fcngliche Wort? (\u00fc = ue, \u00df = ss usw.)<\/p>\n<p><em>Die L\u00f6sung werde ich in ca. 2 Wochen in den Kommentaren ver\u00f6ffentlichen.<\/em><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><a href=\"http:\/\/www.k-engelhardt.de\/knobeleien\/wp-content\/uploads\/2013\/09\/Wortpuzzle-87.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-2303\" alt=\"Wortpuzzle #87\" src=\"http:\/\/www.k-engelhardt.de\/knobeleien\/wp-content\/uploads\/2013\/09\/Wortpuzzle-87.jpg\" width=\"560\" height=\"112\" srcset=\"https:\/\/k-engelhardt.de\/knobeleien\/wp-content\/uploads\/2013\/09\/Wortpuzzle-87.jpg 560w, https:\/\/k-engelhardt.de\/knobeleien\/wp-content\/uploads\/2013\/09\/Wortpuzzle-87-300x60.jpg 300w, https:\/\/k-engelhardt.de\/knobeleien\/wp-content\/uploads\/2013\/09\/Wortpuzzle-87-500x100.jpg 500w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hilfe, die Buchstaben dieses Wortes haben sich komplett neu sortiert. Doch wie war das urspr\u00fcngliche Wort? (\u00fc = ue, \u00df = ss usw.) Die L\u00f6sung werde ich in ca. 2 Wochen in den Kommentaren ver\u00f6ffentlichen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2301","post","type-post","status-publish","format-standard","hentry","category-wortpuzzle"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Klaus\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"R\u00e4tsel &amp; Knobeleien | f\u00fcr alle, die R\u00e4tsel m\u00f6gen.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Wortpuzzle #87 \u2013 Beziehungskiste | R\u00e4tsel &amp; Knobeleien\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-09-23T06:00:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-09-21T09:01:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Wortpuzzle #87 \u2013 Beziehungskiste | R\u00e4tsel &amp; Knobeleien\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#article\",\"name\":\"Wortpuzzle #87 \\u2013 Beziehungskiste | R\\u00e4tsel & Knobeleien\",\"headline\":\"Wortpuzzle #87 &#8211; Beziehungskiste\",\"author\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/author\\\/keinengel\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.k-engelhardt.de\\\/knobeleien\\\/wp-content\\\/uploads\\\/2012\\\/09\\\/cat-wortpuzzle.jpg\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#articleImage\"},\"datePublished\":\"2013-09-23T07:00:22+01:00\",\"dateModified\":\"2013-09-21T10:01:45+01:00\",\"inLanguage\":\"de-DE\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#webpage\"},\"articleSection\":\"Wortpuzzle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/category\\\/wortpuzzle\\\/#listItem\",\"name\":\"Wortpuzzle\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/category\\\/wortpuzzle\\\/#listItem\",\"position\":2,\"name\":\"Wortpuzzle\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/category\\\/wortpuzzle\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#listItem\",\"name\":\"Wortpuzzle #87 &#8211; Beziehungskiste\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#listItem\",\"position\":3,\"name\":\"Wortpuzzle #87 &#8211; Beziehungskiste\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/category\\\/wortpuzzle\\\/#listItem\",\"name\":\"Wortpuzzle\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#organization\",\"name\":\"R\\u00e4tsel & Knobeleien\",\"description\":\"f\\u00fcr alle, die R\\u00e4tsel m\\u00f6gen.\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/author\\\/keinengel\\\/#author\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/author\\\/keinengel\\\/\",\"name\":\"Klaus\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#webpage\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/\",\"name\":\"Wortpuzzle #87 \\u2013 Beziehungskiste | R\\u00e4tsel & Knobeleien\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/wortpuzzle-87-beziehungskiste\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/author\\\/keinengel\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/author\\\/keinengel\\\/#author\"},\"datePublished\":\"2013-09-23T07:00:22+01:00\",\"dateModified\":\"2013-09-21T10:01:45+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#website\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/\",\"name\":\"R\\u00e4tsel & Knobeleien\",\"description\":\"f\\u00fcr alle, die R\\u00e4tsel m\\u00f6gen.\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Wortpuzzle #87 \u2013 Beziehungskiste | R\u00e4tsel & Knobeleien","description":"","canonical_url":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#article","name":"Wortpuzzle #87 \u2013 Beziehungskiste | R\u00e4tsel & Knobeleien","headline":"Wortpuzzle #87 &#8211; Beziehungskiste","author":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/author\/keinengel\/#author"},"publisher":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.k-engelhardt.de\/knobeleien\/wp-content\/uploads\/2012\/09\/cat-wortpuzzle.jpg","@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#articleImage"},"datePublished":"2013-09-23T07:00:22+01:00","dateModified":"2013-09-21T10:01:45+01:00","inLanguage":"de-DE","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#webpage"},"isPartOf":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#webpage"},"articleSection":"Wortpuzzle"},{"@type":"BreadcrumbList","@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien#listItem","position":1,"name":"Home","item":"https:\/\/k-engelhardt.de\/knobeleien","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien\/category\/wortpuzzle\/#listItem","name":"Wortpuzzle"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien\/category\/wortpuzzle\/#listItem","position":2,"name":"Wortpuzzle","item":"https:\/\/k-engelhardt.de\/knobeleien\/category\/wortpuzzle\/","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#listItem","name":"Wortpuzzle #87 &#8211; Beziehungskiste"},"previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#listItem","position":3,"name":"Wortpuzzle #87 &#8211; Beziehungskiste","previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien\/category\/wortpuzzle\/#listItem","name":"Wortpuzzle"}}]},{"@type":"Organization","@id":"https:\/\/k-engelhardt.de\/knobeleien\/#organization","name":"R\u00e4tsel & Knobeleien","description":"f\u00fcr alle, die R\u00e4tsel m\u00f6gen.","url":"https:\/\/k-engelhardt.de\/knobeleien\/"},{"@type":"Person","@id":"https:\/\/k-engelhardt.de\/knobeleien\/author\/keinengel\/#author","url":"https:\/\/k-engelhardt.de\/knobeleien\/author\/keinengel\/","name":"Klaus"},{"@type":"WebPage","@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#webpage","url":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/","name":"Wortpuzzle #87 \u2013 Beziehungskiste | R\u00e4tsel & Knobeleien","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/#website"},"breadcrumb":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/#breadcrumblist"},"author":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/author\/keinengel\/#author"},"creator":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/author\/keinengel\/#author"},"datePublished":"2013-09-23T07:00:22+01:00","dateModified":"2013-09-21T10:01:45+01:00"},{"@type":"WebSite","@id":"https:\/\/k-engelhardt.de\/knobeleien\/#website","url":"https:\/\/k-engelhardt.de\/knobeleien\/","name":"R\u00e4tsel & Knobeleien","description":"f\u00fcr alle, die R\u00e4tsel m\u00f6gen.","inLanguage":"de-DE","publisher":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/#organization"}}]},"og:locale":"de_DE","og:site_name":"R\u00e4tsel &amp; Knobeleien | f\u00fcr alle, die R\u00e4tsel m\u00f6gen.","og:type":"article","og:title":"Wortpuzzle #87 \u2013 Beziehungskiste | R\u00e4tsel &amp; Knobeleien","og:url":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/","article:published_time":"2013-09-23T06:00:22+00:00","article:modified_time":"2013-09-21T09:01:45+00:00","twitter:card":"summary","twitter:title":"Wortpuzzle #87 \u2013 Beziehungskiste | R\u00e4tsel &amp; Knobeleien"},"aioseo_meta_data":{"post_id":"2301","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-29 12:24:36","updated":"2025-06-04 13:05:54","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/knobeleien\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/knobeleien\/category\/wortpuzzle\/\" title=\"Wortpuzzle\">Wortpuzzle<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWortpuzzle #87 \u2013 Beziehungskiste\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/k-engelhardt.de\/knobeleien"},{"label":"Wortpuzzle","link":"https:\/\/k-engelhardt.de\/knobeleien\/category\/wortpuzzle\/"},{"label":"Wortpuzzle #87 &#8211; Beziehungskiste","link":"https:\/\/k-engelhardt.de\/knobeleien\/wortpuzzle-87-beziehungskiste\/"}],"_links":{"self":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/2301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/comments?post=2301"}],"version-history":[{"count":4,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/2301\/revisions"}],"predecessor-version":[{"id":2453,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/posts\/2301\/revisions\/2453"}],"wp:attachment":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/media?parent=2301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/categories?post=2301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/tags?post=2301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}