{"id":3320,"date":"2014-04-14T21:01:37","date_gmt":"2014-04-14T20:01:37","guid":{"rendered":"http:\/\/www.k-engelhardt.de\/knobeleien\/?page_id=3320"},"modified":"2021-11-04T11:51:16","modified_gmt":"2021-11-04T10:51:16","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<h1>Datenschutzerkl\u00e4rung<\/h1>\n<h2>Cookies<\/h2>\n<p>Die Internetseiten verwenden teilweise so genannte Cookies. Cookies richten auf Ihrem Rechner keinen Schaden an und enthalten keine Viren. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner abgelegt werden und die Ihr Browser speichert.<\/p>\n<p>Die meisten der von uns verwendeten Cookies sind so genannte \u201eSession-Cookies\u201c. Sie werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Andere Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese l\u00f6schen. Diese Cookies erm\u00f6glichen es uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen.<\/p>\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browser aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n<h2>Server-Log-Files<\/h2>\n<p>Der Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log Files, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n<ul>\n<li>Browsertyp und Browserversion<\/li>\n<li>verwendetes Betriebssystem<\/li>\n<li>Referrer URL<\/li>\n<li>Hostname des zugreifenden Rechners<\/li>\n<li>Uhrzeit der Serveranfrage<\/li>\n<\/ul>\n<p>Diese Daten sind nicht bestimmten Personen zuordenbar. Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen. Wir behalten uns vor, diese Daten nachtr\u00e4glich zu pr\u00fcfen, wenn uns konkrete Anhaltspunkte f\u00fcr eine rechtswidrige Nutzung bekannt werden.<\/p>\n<h2>Kommentarfunktion auf dieser Website<\/h2>\n<p>F\u00fcr die Kommentarfunktion auf dieser Seite werden neben Ihrem Kommentar auch Angaben zum Zeitpunkt der Erstellung des Kommentars, Ihre E-Mail-Adresse und, wenn Sie nicht anonym posten, der von Ihnen gew\u00e4hlte Nutzername gespeichert.<\/p>\n<p><strong>Speicherung der IP-Adresse<\/strong><\/p>\n<p>Unsere Kommentarfunktion speichert die IP-Adressen der Nutzer, die Kommentare verfassen. Da wir Kommentare auf unserer Seite nicht vor der Freischaltung pr\u00fcfen, ben\u00f6tigen wir diese Daten, um im Falle von Rechtsverletzungen wie Beleidigungen oder Propaganda gegen den Verfasser vorgehen zu k\u00f6nnen.<\/p>\n<h2>SSL-Verschl\u00fcsselung<\/h2>\n<p>Diese Seite nutzt aus Gr\u00fcnden der Sicherheit und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel der Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von &#8222;http:\/\/&#8220; auf &#8222;https:\/\/&#8220; wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n<p>Wenn die SSL-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<h2>Recht auf Auskunft, L\u00f6schung, Sperrung<\/h2>\n<p>Sie haben jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung sowie ein Recht auf Berichtigung, Sperrung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden.<\/p>\n<h2>Widerspruch Werbe-Mails<\/h2>\n<p>Der Nutzung von im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien wird hiermit widersprochen. Die Betreiber der Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n<p>Quelle: <a href=\"https:\/\/www.erecht24.\nde\">eRecht24<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Cookies Die Internetseiten verwenden teilweise so genannte Cookies. Cookies richten auf Ihrem Rechner keinen Schaden an und enthalten keine Viren. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner &hellip; <a href=\"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":15,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3320","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"R\u00e4tsel &amp; Knobeleien | f\u00fcr alle, die R\u00e4tsel m\u00f6gen.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung | R\u00e4tsel &amp; Knobeleien\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-04-14T20:01:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-11-04T10:51:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Datenschutzerkl\u00e4rung | R\u00e4tsel &amp; Knobeleien\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/datenschutzerklaerung\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/datenschutzerklaerung\\\/#listItem\",\"name\":\"Datenschutzerkl\\u00e4rung\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/datenschutzerklaerung\\\/#listItem\",\"position\":2,\"name\":\"Datenschutzerkl\\u00e4rung\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#organization\",\"name\":\"R\\u00e4tsel & Knobeleien\",\"description\":\"f\\u00fcr alle, die R\\u00e4tsel m\\u00f6gen.\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/datenschutzerklaerung\\\/#webpage\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\\u00e4rung | R\\u00e4tsel & Knobeleien\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/datenschutzerklaerung\\\/#breadcrumblist\"},\"datePublished\":\"2014-04-14T21:01:37+01:00\",\"dateModified\":\"2021-11-04T11:51:16+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#website\",\"url\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/\",\"name\":\"R\\u00e4tsel & Knobeleien\",\"description\":\"f\\u00fcr alle, die R\\u00e4tsel m\\u00f6gen.\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-engelhardt.de\\\/knobeleien\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Datenschutzerkl\u00e4rung | R\u00e4tsel & Knobeleien","description":"","canonical_url":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien#listItem","position":1,"name":"Home","item":"https:\/\/k-engelhardt.de\/knobeleien","nextItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/#listItem","name":"Datenschutzerkl\u00e4rung"}},{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/#listItem","position":2,"name":"Datenschutzerkl\u00e4rung","previousItem":{"@type":"ListItem","@id":"https:\/\/k-engelhardt.de\/knobeleien#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/k-engelhardt.de\/knobeleien\/#organization","name":"R\u00e4tsel & Knobeleien","description":"f\u00fcr alle, die R\u00e4tsel m\u00f6gen.","url":"https:\/\/k-engelhardt.de\/knobeleien\/"},{"@type":"WebPage","@id":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/#webpage","url":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung | R\u00e4tsel & Knobeleien","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/#website"},"breadcrumb":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/#breadcrumblist"},"datePublished":"2014-04-14T21:01:37+01:00","dateModified":"2021-11-04T11:51:16+01:00"},{"@type":"WebSite","@id":"https:\/\/k-engelhardt.de\/knobeleien\/#website","url":"https:\/\/k-engelhardt.de\/knobeleien\/","name":"R\u00e4tsel & Knobeleien","description":"f\u00fcr alle, die R\u00e4tsel m\u00f6gen.","inLanguage":"de-DE","publisher":{"@id":"https:\/\/k-engelhardt.de\/knobeleien\/#organization"}}]},"og:locale":"de_DE","og:site_name":"R\u00e4tsel &amp; Knobeleien | f\u00fcr alle, die R\u00e4tsel m\u00f6gen.","og:type":"article","og:title":"Datenschutzerkl\u00e4rung | R\u00e4tsel &amp; Knobeleien","og:url":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/","article:published_time":"2014-04-14T20:01:37+00:00","article:modified_time":"2021-11-04T10:51:16+00:00","twitter:card":"summary","twitter:title":"Datenschutzerkl\u00e4rung | R\u00e4tsel &amp; Knobeleien"},"aioseo_meta_data":{"post_id":"3320","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"#aioseo-web-page-6458c6e53777c","slug":"web-page","graphName":"WebPage","label":"Web Page","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-29 12:09:08","updated":"2025-06-04 10:58:19","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/k-engelhardt.de\/knobeleien\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDatenschutzerkl\u00e4rung\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/k-engelhardt.de\/knobeleien"},{"label":"Datenschutzerkl\u00e4rung","link":"https:\/\/k-engelhardt.de\/knobeleien\/datenschutzerklaerung\/"}],"_links":{"self":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/pages\/3320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/comments?post=3320"}],"version-history":[{"count":5,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/pages\/3320\/revisions"}],"predecessor-version":[{"id":8701,"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/pages\/3320\/revisions\/8701"}],"wp:attachment":[{"href":"https:\/\/k-engelhardt.de\/knobeleien\/wp-json\/wp\/v2\/media?parent=3320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}